{"id":2513,"date":"2025-10-05T01:26:30","date_gmt":"2025-10-05T01:26:30","guid":{"rendered":"https:\/\/guineabiztv.harmattan-mali.com\/?p=2513"},"modified":"2025-10-05T01:26:30","modified_gmt":"2025-10-05T01:26:30","slug":"ita-agro-y-la-francofonia-siembran-educacion-ecologica-en-basakato-del-oeste","status":"publish","type":"post","link":"https:\/\/guineabiztv.harmattan-mali.com\/fr\/ita-agro-y-la-francofonia-siembran-educacion-ecologica-en-basakato-del-oeste\/","title":{"rendered":"ITA-AGRO y la Francofon\u00eda siembran educaci\u00f3n ecol\u00f3gica en Basakato del Oeste"},"content":{"rendered":"<p>Ahora EG<\/p><p><a href=\"https:\/\/guineabiztv.harmattan-mali.com\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-30-at-12.56.56-750x375.jpeg\"><img decoding=\"async\" src=\"https:\/\/guineabiztv.harmattan-mali.com\/wp-content\/uploads\/2025\/10\/WhatsApp-Image-2025-09-30-at-12.56.56-750x375-150x150.jpeg\" width=\"150\" height=\"150\" alt=\"[:es]WhatsApp-Image-2025-09-30-at-12.56.56-750x375.jpeg[:]\" style=\"display:inline-block\"><\/a> <\/p><p>En el Internado Dulce Nombre de Mar\u00eda de Basakato del Oeste, la agricultura ha dejado de ser una simple asignatura, para convertirse en una herramienta real de aprendizaje y futuro. La Organizaci\u00f3n Internacional de la Francofon\u00eda (OIF) y la empresa ITA-AGRO han puesto en marcha all\u00ed el proyecto \u00abJ\u00f3venes Ra\u00edces\u00bb; una iniciativa que pretende inculcar conciencia ecol\u00f3gica y responsabilidad alimentaria desde las aulas.<br \/>\nEl lanzamiento oficial tuvo lugar ayer lunes, 29 de septiembre de 2025 contando con la presencia de representantes de la OIF y de ITA-AGRO. El centro ha sido seleccionado como piloto de un programa que se inscribe en el compromiso de la Francofon\u00eda con las acciones ecol\u00f3gicas en la Cuenca del Congo.<\/p>\n<p>Lejos de quedarse en los discursos, el proyecto incluye infraestructura concreta: un gallinero y una nave destinada al cultivo de hortalizas. Estos espacios permitir\u00e1n que los alumnos y alumnas del internado aprendan t\u00e9cnicas b\u00e1sicas de producci\u00f3n agr\u00edcola y av\u00edcola. El objetivo es que los j\u00f3venes entiendan su papel en la seguridad alimentaria y descubran que el desarrollo comunitario puede comenzar en un huerto escolar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ahora EG En el Internado Dulce Nombre de Mar\u00eda de Basakato del Oeste, la agricultura ha dejado de ser una simple asignatura, para convertirse en una herramienta real de aprendizaje y futuro. La Organizaci\u00f3n Internacional de la Francofon\u00eda (OIF) y la empresa ITA-AGRO han puesto en marcha all\u00ed el proyecto \u00abJ\u00f3venes Ra\u00edces\u00bb; una iniciativa que pretende inculcar conciencia ecol\u00f3gica y responsabilidad alimentaria desde las aulas. El lanzamiento oficial tuvo lugar ayer lunes, 29 de septiembre de 2025 contando con la presencia de representantes de la OIF y de ITA-AGRO. El centro ha sido seleccionado como piloto de un programa que se inscribe en el compromiso de la Francofon\u00eda con las acciones ecol\u00f3gicas en la Cuenca del Congo. Lejos de quedarse en los discursos, el proyecto incluye infraestructura concreta: un gallinero y una nave destinada al cultivo de hortalizas. Estos espacios permitir\u00e1n que los alumnos y alumnas del internado aprendan t\u00e9cnicas b\u00e1sicas de producci\u00f3n agr\u00edcola y av\u00edcola. El objetivo es que los j\u00f3venes entiendan su papel en la seguridad alimentaria y descubran que el desarrollo comunitario puede comenzar en un huerto escolar.<\/p>\n","protected":false},"author":1,"featured_media":2515,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/guineabiztv.harmattan-mali.com\/fr\/wp-json\/wp\/v2\/posts\/2513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guineabiztv.harmattan-mali.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guineabiztv.harmattan-mali.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guineabiztv.harmattan-mali.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/guineabiztv.harmattan-mali.com\/fr\/wp-json\/wp\/v2\/comments?post=2513"}],"version-history":[{"count":1,"href":"https:\/\/guineabiztv.harmattan-mali.com\/fr\/wp-json\/wp\/v2\/posts\/2513\/revisions"}],"predecessor-version":[{"id":2514,"href":"https:\/\/guineabiztv.harmattan-mali.com\/fr\/wp-json\/wp\/v2\/posts\/2513\/revisions\/2514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guineabiztv.harmattan-mali.com\/fr\/wp-json\/wp\/v2\/media\/2515"}],"wp:attachment":[{"href":"https:\/\/guineabiztv.harmattan-mali.com\/fr\/wp-json\/wp\/v2\/media?parent=2513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guineabiztv.harmattan-mali.com\/fr\/wp-json\/wp\/v2\/categories?post=2513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guineabiztv.harmattan-mali.com\/fr\/wp-json\/wp\/v2\/tags?post=2513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}